{"id":618,"date":"2021-06-07T14:04:19","date_gmt":"2021-06-07T14:04:19","guid":{"rendered":"https:\/\/limamarket.com.ar\/home\/?post_type=product&#038;p=618"},"modified":"2025-08-12T20:09:00","modified_gmt":"2025-08-12T20:09:00","slug":"cepillo-de-dientes-kids","status":"publish","type":"product","link":"https:\/\/limamarket.com.ar\/home\/producto\/cepillo-de-dientes-kids\/","title":{"rendered":"Cepillo de dientes Kids Meraki"},"content":{"rendered":"<p>\u2013 Misma vida \u00fatil y experiencia de lavado que un cepillo de dientes convencional.<br \/>\n\u2013 97% biodegradables: packaging de cart\u00f3n y mango de bamb\u00fa moso.<br \/>\n\u2013 3% reciclable: cerdas de Nylon libres de BPA.<br \/>\n\u2013 Una vez que termines de utilizar tu cepillo, separ\u00e1 las cerdas con una pinza y descart\u00e1 las cerdas junto con tus residuos reciclables.<br \/>\n\u2013 El packaging y mango pueden ser compostados.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u2013 Misma vida \u00fatil y experiencia de lavado que un cepillo de dientes convencional. \u2013 97% biodegradables: packaging de cart\u00f3n y mango de bamb\u00fa moso. \u2013 3% reciclable: cerdas de Nylon libres de BPA. \u2013 Una vez que termines de utilizar tu cepillo, separ\u00e1 las cerdas con una pinza y descart\u00e1 las cerdas junto con [&#8230;]\n","protected":false},"featured_media":619,"template":"","meta":{"_joinchat":[]},"product_cat":[438,29,33],"product_tag":[194],"_links":{"self":[{"href":"https:\/\/limamarket.com.ar\/home\/wp-json\/wp\/v2\/product\/618"}],"collection":[{"href":"https:\/\/limamarket.com.ar\/home\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/limamarket.com.ar\/home\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/limamarket.com.ar\/home\/wp-json\/wp\/v2\/media\/619"}],"wp:attachment":[{"href":"https:\/\/limamarket.com.ar\/home\/wp-json\/wp\/v2\/media?parent=618"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/limamarket.com.ar\/home\/wp-json\/wp\/v2\/product_cat?post=618"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/limamarket.com.ar\/home\/wp-json\/wp\/v2\/product_tag?post=618"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}