{"id":3365,"date":"2022-04-14T22:23:35","date_gmt":"2022-04-14T22:23:35","guid":{"rendered":"https:\/\/limamarket.com.ar\/home\/?post_type=product&#038;p=3365"},"modified":"2025-07-15T15:43:28","modified_gmt":"2025-07-15T15:43:28","slug":"suavizante-para-ropa-campos-de-flores-x-5-litros","status":"publish","type":"product","link":"https:\/\/limamarket.com.ar\/home\/producto\/suavizante-para-ropa-campos-de-flores-x-5-litros\/","title":{"rendered":"Suavizante para ropa Campos de Flores x 5 litros"},"content":{"rendered":"<p>El producto es un acondicionador de todo tipo de telas con la capacidad de dar un aspecto de suavidad al tacto.<\/p>\n<p>La cantidad recomendada es de 100ml por carga normal de 5kgs.<\/p>\n<h4>\u00bfQu\u00e9 es?<\/h4>\n<p>El producto es un acondicionador de todo tipo de telas con la capacidad de dar un aspecto de suavidad al tacto.<\/p>\n<h4>\u00bfC\u00f3mo se usa?<\/h4>\n<p>La cantidad recomendada es de 100ml por carga normal de 5kgs. Colocar el producto en la gabeta especifica del lavarropas. En caso de no descargar, agregra agua y agitar hasta que sea fluido.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El producto es un acondicionador de todo tipo de telas con la capacidad de dar un aspecto de suavidad al tacto. La cantidad recomendada es de 100ml por carga normal de 5kgs. \u00bfQu\u00e9 es? El producto es un acondicionador de todo tipo de telas con la capacidad de dar un aspecto de suavidad al tacto. [&#8230;]\n","protected":false},"featured_media":3366,"template":"","meta":{"_joinchat":[]},"product_cat":[16,18],"product_tag":[759],"_links":{"self":[{"href":"https:\/\/limamarket.com.ar\/home\/wp-json\/wp\/v2\/product\/3365"}],"collection":[{"href":"https:\/\/limamarket.com.ar\/home\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/limamarket.com.ar\/home\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/limamarket.com.ar\/home\/wp-json\/wp\/v2\/media\/3366"}],"wp:attachment":[{"href":"https:\/\/limamarket.com.ar\/home\/wp-json\/wp\/v2\/media?parent=3365"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/limamarket.com.ar\/home\/wp-json\/wp\/v2\/product_cat?post=3365"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/limamarket.com.ar\/home\/wp-json\/wp\/v2\/product_tag?post=3365"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}